{"id":2473,"date":"2024-05-14T05:06:18","date_gmt":"2024-05-14T15:06:18","guid":{"rendered":"https:\/\/konarentals.com\/?p=2473"},"modified":"2024-05-20T04:49:00","modified_gmt":"2024-05-20T14:49:00","slug":"north-kohala-kamehameha-day-celebration","status":"publish","type":"post","link":"https:\/\/konarentals.com\/de\/2024\/05\/14\/north-kohala-kamehameha-day-celebration\/","title":{"rendered":"Ein Erbe ehren: Die Feier zum North Kohala Kamehameha Day"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Jedes Jahr zeugt die North Kohala Kamehameha Day Celebration vom anhaltenden Geist des Aloha und der Verehrung f\u00fcr den hawaiianischen Monarchen Kamehameha I., dessen Geburtstag am 11. Juni begangen wird.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-2474\" src=\"https:\/\/konarentals.com\/wp-content\/uploads\/Statue-of-King-Kamehameha-300x169.png\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/konarentals.com\/wp-content\/uploads\/Statue-of-King-Kamehameha-300x169.png 300w, https:\/\/konarentals.com\/wp-content\/uploads\/Statue-of-King-Kamehameha-1030x579.png 1030w, https:\/\/konarentals.com\/wp-content\/uploads\/Statue-of-King-Kamehameha-768x432.png 768w, https:\/\/konarentals.com\/wp-content\/uploads\/Statue-of-King-Kamehameha-1536x864.png 1536w, https:\/\/konarentals.com\/wp-content\/uploads\/Statue-of-King-Kamehameha-2048x1152.png 2048w, https:\/\/konarentals.com\/wp-content\/uploads\/Statue-of-King-Kamehameha-1500x844.png 1500w, https:\/\/konarentals.com\/wp-content\/uploads\/Statue-of-King-Kamehameha-705x397.png 705w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Am Geburtsort von Kamehameha I. gelegen, zieht dieses Fest Tausende von Besuchern von den Hawaii-Inseln und dar\u00fcber hinaus an und schafft ein lebendiges Geflecht aus Kultur, Tradition und Gemeinschaft. Wenn die Sonne \u00fcber der ruhigen Landschaft aufgeht, entfalten sich die Festlichkeiten und bilden einen ganzen Tag voller Aktivit\u00e4ten, die dem verehrten K\u00f6nig und seinem bleibenden Verm\u00e4chtnis huldigen.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Eine vision\u00e4re F\u00fchrungspers\u00f6nlichkeit<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Im Mittelpunkt der Feierlichkeiten steht der tiefe Respekt vor Kamehameha I., dem vision\u00e4ren F\u00fchrer, der die hawaiianischen Inseln Ende des 18. Jahrhunderts unter einer einzigen Herrschaft vereinte. Der Tag beginnt mit einer k\u00f6niglichen Prozession, einer majest\u00e4tischen Zurschaustellung der hawaiianischen Kultur und des hawaiianischen Erbes, bei der die traditionell gekleideten Teilnehmer durch die Stra\u00dfen ziehen, begleitet vom rhythmischen Schlag der Trommeln und den melodi\u00f6sen Ges\u00e4ngen der Oli. Dieser feierliche und doch fr\u00f6hliche Marsch gibt den Ton f\u00fcr den kommenden Tag an und symbolisiert Einheit, St\u00e4rke und den unbezwingbaren Geist des hawaiianischen Volkes.<\/span><\/p>\n<h3>J\u00e4hrliche Parade<\/h3>\n<p><span style=\"font-weight: 400;\">Im Anschluss an die Prozession erwacht die Stadt Kapa'au mit den leuchtenden Farben und Kl\u00e4ngen der j\u00e4hrlichen Parade zum Leben. Mit duftenden Blumen und kunstvollen Mustern geschm\u00fcckte Wagen gleiten durch die Stra\u00dfen, jeder einzelne ein Zeugnis der reichen hawaiianischen Geschichte und Kultur. Von traditionellen Hula-T\u00e4nzerinnen, die sich anmutig im Takt der Trommeln wiegen, bis hin zu lebhaften Darbietungen, die die Kunst des Poi-Schlagens und des Lauhala-Webens zeigen, verk\u00f6rpert die Parade das Wesen der hawaiianischen Identit\u00e4t und l\u00e4dt die Zuschauer ein, in die Sch\u00f6nheit und den Rhythmus der Inseln einzutauchen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Im Mittelpunkt der Feierlichkeiten steht die Zeremonie des Lei-Bindens, die am Fu\u00dfe der Kamehameha-I-Statue in Kapa'au stattfindet. Hier versammeln sich die Teilnehmer inmitten eines duftenden Bl\u00fctenmeeres und mit leuchtenden Farben geschm\u00fcckter Blumenketten, um dem gro\u00dfen K\u00f6nig ihren Respekt zu erweisen. Ehrfurchtsvoll und feierlich wird jeder einzelne Blumenkranz auf die Statue gelegt, ein Symbol der Liebe, der Ehre und der Erinnerung an Kamehameha I. und seine tiefgreifenden Beitr\u00e4ge zur hawaiianischen Gesellschaft. Diese ergreifende Zeremonie erinnert an das bleibende Verm\u00e4chtnis des Monarchen, dessen Visionen und F\u00fchrungsqualit\u00e4ten noch immer Generationen inspirieren.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">P\u00e4dagogische Exponate<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Zus\u00e4tzlich zu den zeremoniellen Abl\u00e4ufen bietet die Feier eine Reihe von interaktiven, lehrreichen Ausstellungen, die den Besuchern die M\u00f6glichkeit geben, tiefer in die hawaiianische Geschichte, Kultur und Traditionen einzutauchen. Von Vorf\u00fchrungen traditioneller Handwerksk\u00fcnste wie der Kapa-Herstellung und dem Weben von Fischernetzen bis hin zu informativen Ausstellungen, die die Bedeutung alter hawaiianischer Wahrzeichen hervorheben, bieten diese Ausstellungen einen Einblick in das reiche hawaiianische Erbe und f\u00f6rdern eine tiefere Wertsch\u00e4tzung f\u00fcr das Land und seine Menschen.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Spa\u00df f\u00fcr Keiki<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u00dcber ihre kulturelle Bedeutung hinaus dient die North Kohala Kamehameha Day Celebration als Leuchtfeuer des Gemeinschaftsgeistes und der Einheit und bringt Menschen aus allen Gesellschaftsschichten zusammen, um ein gemeinsames Erbe und Verm\u00e4chtnis zu feiern. Von den temperamentvollen Ges\u00e4ngen der Keiki bis hin zur Weisheit der Kupuna verk\u00f6rpert die Feier den Geist des Aloha, f\u00f6rdert Verbindungen und schmiedet Bande, die Zeit und Raum \u00fcberdauern.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">W\u00e4hrend die Sonne \u00fcber einem weiteren Tag des Feierns untergeht, liegt das Echo der Ges\u00e4nge und des Lachens in der Luft, ein Zeugnis f\u00fcr das bleibende Verm\u00e4chtnis von Kamehameha I. und den lebendigen Geist des hawaiianischen Volkes. Im Herzen von Nord-Kohala, inmitten der \u00fcppigen Sch\u00f6nheit des Landes, steht die j\u00e4hrliche Kamehameha Day Celebration als lebendige Hommage an einen K\u00f6nig, dessen Verm\u00e4chtnis weiterhin Generationen inspiriert und vereint und sicherstellt, dass sein Andenken f\u00fcr immer im Gewebe der hawaiianischen Kultur und Geschichte verankert bleibt.<br \/>\nF\u00fcr weitere Informationen zum Festival <a href=\"http:\/\/www.kamehamehadaycelebration.org\/\">klicken Sie hier.<\/a><\/span><\/p>\n<p>Suchen Sie eine Unterkunft? Sehen Sie sich an, was wir haben<a href=\"https:\/\/konarentals.com\/hawaii-vacation-rentals\/m\/\">\u00a0verf\u00fcgbar f\u00fcr Ihre Termine<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Every year the North Kohala Kamehameha Day Celebration stands as a testament to the enduring spirit of aloha and the reverence for Hawaiian monarch Kamehameha I, commemorated annually on his birthday, June 11. Nestled in the very birthplace of Kamehameha I, this celebration draws thousands of attendees from across the Hawaiian Islands and beyond, creating [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":2474,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[243],"tags":[139,108,140,112],"class_list":["post-2473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events-in-kailua-kona","tag-big-island-events","tag-events-on-kona","tag-hawaiian-traditions","tag-things-to-do-in-kona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Honoring a Legacy: The North Kohala Kamehameha Day Celebration | Kona Vacation Rentals<\/title>\n<meta name=\"description\" content=\"The vibrant festivities of the North Kohala Kamehameha Day Celebration, honoring Hawaiian monarch Kamehameha I on his birthday.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/konarentals.com\/de\/2024\/05\/14\/north-kohala-kamehameha-day-celebration\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Honoring a Legacy: The North Kohala Kamehameha Day Celebration | Kona Vacation Rentals\" \/>\n<meta property=\"og:description\" content=\"The vibrant festivities of the North Kohala Kamehameha Day Celebration, honoring Hawaiian monarch Kamehameha I on his birthday.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/konarentals.com\/de\/2024\/05\/14\/north-kohala-kamehameha-day-celebration\/\" \/>\n<meta property=\"og:site_name\" content=\"Kona Vacation Rentals\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KonaVacationRent\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-14T15:06:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-20T14:49:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/konarentals.com\/wp-content\/uploads\/Statue-of-King-Kamehameha-1030x579.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1030\" \/>\n\t<meta property=\"og:image:height\" content=\"579\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jennifer Conway\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@KonaVacaRentals\" \/>\n<meta name=\"twitter:site\" content=\"@KonaVacaRentals\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jennifer Conway\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/konarentals.com\\\/2024\\\/05\\\/14\\\/north-kohala-kamehameha-day-celebration\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/konarentals.com\\\/2024\\\/05\\\/14\\\/north-kohala-kamehameha-day-celebration\\\/\"},\"author\":{\"name\":\"Jennifer Conway\",\"@id\":\"https:\\\/\\\/konarentals.com\\\/#\\\/schema\\\/person\\\/6ef892bae07fe46065afdc60151cea7a\"},\"headline\":\"Honoring a Legacy: The North Kohala Kamehameha Day Celebration\",\"datePublished\":\"2024-05-14T15:06:18+00:00\",\"dateModified\":\"2024-05-20T14:49:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/konarentals.com\\\/2024\\\/05\\\/14\\\/north-kohala-kamehameha-day-celebration\\\/\"},\"wordCount\":627,\"publisher\":{\"@id\":\"https:\\\/\\\/konarentals.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/konarentals.com\\\/2024\\\/05\\\/14\\\/north-kohala-kamehameha-day-celebration\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/konarentals.com\\\/wp-content\\\/uploads\\\/Statue-of-King-Kamehameha.png\",\"keywords\":[\"Big Island Events\",\"events on Kona\",\"Hawaiian Traditions\",\"things to do in Kona\"],\"articleSection\":[\"Events in Kailua-Kona\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/konarentals.com\\\/2024\\\/05\\\/14\\\/north-kohala-kamehameha-day-celebration\\\/\",\"url\":\"https:\\\/\\\/konarentals.com\\\/2024\\\/05\\\/14\\\/north-kohala-kamehameha-day-celebration\\\/\",\"name\":\"Honoring a Legacy: The North Kohala Kamehameha Day Celebration | Kona Vacation Rentals\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/konarentals.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/konarentals.com\\\/2024\\\/05\\\/14\\\/north-kohala-kamehameha-day-celebration\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/konarentals.com\\\/2024\\\/05\\\/14\\\/north-kohala-kamehameha-day-celebration\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/konarentals.com\\\/wp-content\\\/uploads\\\/Statue-of-King-Kamehameha.png\",\"datePublished\":\"2024-05-14T15:06:18+00:00\",\"dateModified\":\"2024-05-20T14:49:00+00:00\",\"description\":\"The vibrant festivities of the North Kohala Kamehameha Day Celebration, honoring Hawaiian monarch Kamehameha I on his birthday.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/konarentals.com\\\/2024\\\/05\\\/14\\\/north-kohala-kamehameha-day-celebration\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/konarentals.com\\\/2024\\\/05\\\/14\\\/north-kohala-kamehameha-day-celebration\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/konarentals.com\\\/2024\\\/05\\\/14\\\/north-kohala-kamehameha-day-celebration\\\/#primaryimage\",\"url\":\"https:\\\/\\\/konarentals.com\\\/wp-content\\\/uploads\\\/Statue-of-King-Kamehameha.png\",\"contentUrl\":\"https:\\\/\\\/konarentals.com\\\/wp-content\\\/uploads\\\/Statue-of-King-Kamehameha.png\",\"width\":2400,\"height\":1350,\"caption\":\"Statue of King Kamehameha\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/konarentals.com\\\/2024\\\/05\\\/14\\\/north-kohala-kamehameha-day-celebration\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/konarentals.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Honoring a Legacy: The North Kohala Kamehameha Day Celebration\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/konarentals.com\\\/#website\",\"url\":\"https:\\\/\\\/konarentals.com\\\/\",\"name\":\"Kona Vacation Rentals\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/konarentals.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/konarentals.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/konarentals.com\\\/#organization\",\"name\":\"Kona Vacation Rentals\",\"url\":\"https:\\\/\\\/konarentals.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/konarentals.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/konarentals.com\\\/wp-content\\\/uploads\\\/logo_kona_vacation_rentals.png\",\"contentUrl\":\"https:\\\/\\\/konarentals.com\\\/wp-content\\\/uploads\\\/logo_kona_vacation_rentals.png\",\"width\":680,\"height\":312,\"caption\":\"Kona Vacation Rentals\"},\"image\":{\"@id\":\"https:\\\/\\\/konarentals.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/KonaVacationRent\\\/\",\"https:\\\/\\\/x.com\\\/KonaVacaRentals\",\"https:\\\/\\\/www.instagram.com\\\/konarentals\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCf_-En6qXXWDBPnWcxd1LZg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/konarentals.com\\\/#\\\/schema\\\/person\\\/6ef892bae07fe46065afdc60151cea7a\",\"name\":\"Jennifer Conway\",\"url\":\"https:\\\/\\\/konarentals.com\\\/de\\\/author\\\/konajennifer2022\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Honoring a Legacy: The North Kohala Kamehameha Day Celebration | Kona Vacation Rentals","description":"The vibrant festivities of the North Kohala Kamehameha Day Celebration, honoring Hawaiian monarch Kamehameha I on his birthday.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/konarentals.com\/de\/2024\/05\/14\/north-kohala-kamehameha-day-celebration\/","og_locale":"de_DE","og_type":"article","og_title":"Honoring a Legacy: The North Kohala Kamehameha Day Celebration | Kona Vacation Rentals","og_description":"The vibrant festivities of the North Kohala Kamehameha Day Celebration, honoring Hawaiian monarch Kamehameha I on his birthday.","og_url":"https:\/\/konarentals.com\/de\/2024\/05\/14\/north-kohala-kamehameha-day-celebration\/","og_site_name":"Kona Vacation Rentals","article_publisher":"https:\/\/www.facebook.com\/KonaVacationRent\/","article_published_time":"2024-05-14T15:06:18+00:00","article_modified_time":"2024-05-20T14:49:00+00:00","og_image":[{"width":1030,"height":579,"url":"https:\/\/konarentals.com\/wp-content\/uploads\/Statue-of-King-Kamehameha-1030x579.png","type":"image\/png"}],"author":"Jennifer Conway","twitter_card":"summary_large_image","twitter_creator":"@KonaVacaRentals","twitter_site":"@KonaVacaRentals","twitter_misc":{"Written by":"Jennifer Conway","Est. reading time":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/konarentals.com\/2024\/05\/14\/north-kohala-kamehameha-day-celebration\/#article","isPartOf":{"@id":"https:\/\/konarentals.com\/2024\/05\/14\/north-kohala-kamehameha-day-celebration\/"},"author":{"name":"Jennifer Conway","@id":"https:\/\/konarentals.com\/#\/schema\/person\/6ef892bae07fe46065afdc60151cea7a"},"headline":"Honoring a Legacy: The North Kohala Kamehameha Day Celebration","datePublished":"2024-05-14T15:06:18+00:00","dateModified":"2024-05-20T14:49:00+00:00","mainEntityOfPage":{"@id":"https:\/\/konarentals.com\/2024\/05\/14\/north-kohala-kamehameha-day-celebration\/"},"wordCount":627,"publisher":{"@id":"https:\/\/konarentals.com\/#organization"},"image":{"@id":"https:\/\/konarentals.com\/2024\/05\/14\/north-kohala-kamehameha-day-celebration\/#primaryimage"},"thumbnailUrl":"https:\/\/konarentals.com\/wp-content\/uploads\/Statue-of-King-Kamehameha.png","keywords":["Big Island Events","events on Kona","Hawaiian Traditions","things to do in Kona"],"articleSection":["Events in Kailua-Kona"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/konarentals.com\/2024\/05\/14\/north-kohala-kamehameha-day-celebration\/","url":"https:\/\/konarentals.com\/2024\/05\/14\/north-kohala-kamehameha-day-celebration\/","name":"Honoring a Legacy: The North Kohala Kamehameha Day Celebration | Kona Vacation Rentals","isPartOf":{"@id":"https:\/\/konarentals.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/konarentals.com\/2024\/05\/14\/north-kohala-kamehameha-day-celebration\/#primaryimage"},"image":{"@id":"https:\/\/konarentals.com\/2024\/05\/14\/north-kohala-kamehameha-day-celebration\/#primaryimage"},"thumbnailUrl":"https:\/\/konarentals.com\/wp-content\/uploads\/Statue-of-King-Kamehameha.png","datePublished":"2024-05-14T15:06:18+00:00","dateModified":"2024-05-20T14:49:00+00:00","description":"The vibrant festivities of the North Kohala Kamehameha Day Celebration, honoring Hawaiian monarch Kamehameha I on his birthday.","breadcrumb":{"@id":"https:\/\/konarentals.com\/2024\/05\/14\/north-kohala-kamehameha-day-celebration\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/konarentals.com\/2024\/05\/14\/north-kohala-kamehameha-day-celebration\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/konarentals.com\/2024\/05\/14\/north-kohala-kamehameha-day-celebration\/#primaryimage","url":"https:\/\/konarentals.com\/wp-content\/uploads\/Statue-of-King-Kamehameha.png","contentUrl":"https:\/\/konarentals.com\/wp-content\/uploads\/Statue-of-King-Kamehameha.png","width":2400,"height":1350,"caption":"Statue of King Kamehameha"},{"@type":"BreadcrumbList","@id":"https:\/\/konarentals.com\/2024\/05\/14\/north-kohala-kamehameha-day-celebration\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/konarentals.com\/"},{"@type":"ListItem","position":2,"name":"Honoring a Legacy: The North Kohala Kamehameha Day Celebration"}]},{"@type":"WebSite","@id":"https:\/\/konarentals.com\/#website","url":"https:\/\/konarentals.com\/","name":"Kona-Ferienwohnungen","description":"","publisher":{"@id":"https:\/\/konarentals.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/konarentals.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/konarentals.com\/#organization","name":"Kona-Ferienwohnungen","url":"https:\/\/konarentals.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/konarentals.com\/#\/schema\/logo\/image\/","url":"https:\/\/konarentals.com\/wp-content\/uploads\/logo_kona_vacation_rentals.png","contentUrl":"https:\/\/konarentals.com\/wp-content\/uploads\/logo_kona_vacation_rentals.png","width":680,"height":312,"caption":"Kona Vacation Rentals"},"image":{"@id":"https:\/\/konarentals.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KonaVacationRent\/","https:\/\/x.com\/KonaVacaRentals","https:\/\/www.instagram.com\/konarentals\/","https:\/\/www.youtube.com\/channel\/UCf_-En6qXXWDBPnWcxd1LZg"]},{"@type":"Person","@id":"https:\/\/konarentals.com\/#\/schema\/person\/6ef892bae07fe46065afdc60151cea7a","name":"Jennifer Conway","url":"https:\/\/konarentals.com\/de\/author\/konajennifer2022\/"}]}},"_links":{"self":[{"href":"https:\/\/konarentals.com\/de\/wp-json\/wp\/v2\/posts\/2473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/konarentals.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/konarentals.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/konarentals.com\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/konarentals.com\/de\/wp-json\/wp\/v2\/comments?post=2473"}],"version-history":[{"count":0,"href":"https:\/\/konarentals.com\/de\/wp-json\/wp\/v2\/posts\/2473\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/konarentals.com\/de\/wp-json\/wp\/v2\/media\/2474"}],"wp:attachment":[{"href":"https:\/\/konarentals.com\/de\/wp-json\/wp\/v2\/media?parent=2473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/konarentals.com\/de\/wp-json\/wp\/v2\/categories?post=2473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/konarentals.com\/de\/wp-json\/wp\/v2\/tags?post=2473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}